﻿{"id":268,"date":"1999-04-09T17:05:23","date_gmt":"1999-04-09T17:05:23","guid":{"rendered":"http:\/\/www.abrademi.com\/?p=268"},"modified":"2012-12-20T20:45:58","modified_gmt":"2012-12-20T20:45:58","slug":"reflexoes-no-final-do-milenio-sobre-a-paz","status":"publish","type":"post","link":"https:\/\/www.abrademi.com\/index.php\/reflexoes-no-final-do-milenio-sobre-a-paz\/","title":{"rendered":"Reflex\u00c3\u00b5es no final do mil\u00c3\u00aanio sobre a paz"},"content":{"rendered":"<p><a href=\"https:\/\/www.abrademi.com\/?attachment_id=269\" rel=\"attachment wp-att-269\"><img data-attachment-id=\"269\" data-permalink=\"https:\/\/www.abrademi.com\/index.php\/reflexoes-no-final-do-milenio-sobre-a-paz\/090499paz\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.abrademi.com\/wp-content\/uploads\/2012\/12\/090499paz.jpg?fit=250%2C160&amp;ssl=1\" data-orig-size=\"250,160\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"090499paz\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.abrademi.com\/wp-content\/uploads\/2012\/12\/090499paz.jpg?fit=250%2C160&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.abrademi.com\/wp-content\/uploads\/2012\/12\/090499paz.jpg?fit=250%2C160&amp;ssl=1\" loading=\"lazy\" class=\"alignleft size-full wp-image-269\" alt=\"090499paz\" src=\"https:\/\/i0.wp.com\/www.abrademi.com\/wp-content\/uploads\/2012\/12\/090499paz.jpg?resize=250%2C160&#038;ssl=1\" width=\"250\" height=\"160\" data-recalc-dims=\"1\" \/><\/a>Chegamos ao final do mil\u00c3\u00aanio sem aprendermos o significado da palavra &#8220;paz&#8221;. A tecnologia avan\u00c3\u00a7ou, o homem viaja pelo espa\u00c3\u00a7o, a ci\u00c3\u00aancia encontra solu\u00c3\u00a7\u00c3\u00b5es para muitas doen\u00c3\u00a7as, e o ser humano tamb\u00c3\u00a9m evoluiu. Mas as guerras continuam. O objetivo do evento \u00c3\u00a9 a conscientiza\u00c3\u00a7\u00c3\u00a3o, principalmente dos mais jovens quanto aos horrores da guerra.<\/p>\n<p><b>Data<\/b>:\u00c2\u00a08 de maio &#8211; s\u00c3\u00a1bado<br \/>\n<b>In\u00c3\u00adcio<\/b>:\u00c2\u00a017 horas<br \/>\n<b>Local<\/b>:\u00c2\u00a0Espa\u00c3\u00a7o Cultural Soto Zenshu &#8211; Templo Busshinji<br \/>\nRua S\u00c3\u00a3o Joaquim, 285 &#8211; Liberdade &#8211; S\u00c3\u00a3o Paulo \/ SP<br \/>\n<b>Telefone<\/b>:\u00c2\u00a0(011) 278-4515 e 278-4345<\/p>\n<p><b>Programa\u00c3\u00a7\u00c3\u00a3o<\/b>:<\/p>\n<ul>\n<li>Exposi\u00c3\u00a7\u00c3\u00a3o de fotografias de Hiroshima ap\u00c3\u00b3s a bomba.<\/li>\n<li>Lan\u00c3\u00a7amento do Livro Gen-P\u00c3\u00a9s Descal\u00c3\u00a7os, que conta a inf\u00c3\u00a2ncia de um sobrevivente na forma de mang\u00c3\u00a1 (quadrinhos).<\/li>\n<li>Lan\u00c3\u00a7amento do Concurso de Desenho pela Paz.<\/li>\n<li>Exibi\u00c3\u00a7\u00c3\u00a3o cont\u00c3\u00adnua de Gen-P\u00c3\u00a9s Descal\u00c3\u00a7os em desenho animado e document\u00c3\u00a1rio sobre Hiroshima.<\/li>\n<\/ul>\n<p><b>Palestras<\/b>:<\/p>\n<ul>\n<li><b>18:30 &#8211; Abertura<\/b><br \/>\nLi\u00c3\u00a7\u00c3\u00b5es da Hist\u00c3\u00b3ria Recente na Cultura Japonesa<br \/>\nCristiane A. Sato, presidente da Abrademi.<\/li>\n<\/ul>\n<ul>\n<li><b>19:00 &#8211; O Relato Pessoal de Quem Sobreviveu<\/b><br \/>\nMorita, presidente da Associa\u00c3\u00a7\u00c3\u00a3o das V\u00c3\u00adtimas da Bomba At\u00c3\u00b4mica.<br \/>\nTradu\u00c3\u00a7\u00c3\u00a3o consecutiva e coment\u00c3\u00a1rios de Francisco N. Sato, vice-presidente da Comunidade Budista Soto Zenshu da Am\u00c3\u00a9rica do Sul e diretor da Abrademi.<\/li>\n<\/ul>\n<ul>\n<li><b>20:00 &#8211; Encerramento<\/b><br \/>\nO Significado da Guerra para o Budismo<br \/>\nRev. Monja Coen Murayama, Mission\u00c3\u00a1ria Superior da Soto Zenshu para a Am\u00c3\u00a9rica do Sul.<\/li>\n<\/ul>\n<ul>\n<li><b>20:30 &#8211; perguntas \/ debate<\/b><\/li>\n<\/ul>\n<p style=\"text-align: left;\">\n<b>Realiza\u00c3\u00a7\u00c3\u00a3o<\/b>:<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.abrademi.com\/?attachment_id=270\" rel=\"attachment wp-att-270\"><img data-attachment-id=\"270\" data-permalink=\"https:\/\/www.abrademi.com\/index.php\/reflexoes-no-final-do-milenio-sobre-a-paz\/reflexaopaz-organizadores\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.abrademi.com\/wp-content\/uploads\/2012\/12\/reflexaopaz-organizadores.jpg?fit=545%2C114&amp;ssl=1\" data-orig-size=\"545,114\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"reflexaopaz-organizadores\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.abrademi.com\/wp-content\/uploads\/2012\/12\/reflexaopaz-organizadores.jpg?fit=300%2C62&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.abrademi.com\/wp-content\/uploads\/2012\/12\/reflexaopaz-organizadores.jpg?fit=545%2C114&amp;ssl=1\" loading=\"lazy\" class=\"size-full wp-image-270 aligncenter\" alt=\"reflexaopaz-organizadores\" src=\"https:\/\/i0.wp.com\/www.abrademi.com\/wp-content\/uploads\/2012\/12\/reflexaopaz-organizadores.jpg?resize=545%2C114&#038;ssl=1\" width=\"545\" height=\"114\" srcset=\"https:\/\/i0.wp.com\/www.abrademi.com\/wp-content\/uploads\/2012\/12\/reflexaopaz-organizadores.jpg?w=545&amp;ssl=1 545w, https:\/\/i0.wp.com\/www.abrademi.com\/wp-content\/uploads\/2012\/12\/reflexaopaz-organizadores.jpg?resize=300%2C62&amp;ssl=1 300w\" sizes=\"(max-width: 545px) 100vw, 545px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><b>Apoio<\/b>:<br \/>\nEditora Conrad, Associa\u00c3\u00a7\u00c3\u00a3o das V\u00c3\u00adtimas da Bomba At\u00c3\u00b4mica, Greenpeace-Brasil,<br \/>\nImprota Gr\u00c3\u00a1fica e Escola de Arte Igayara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chegamos ao final do mil\u00c3\u00aanio sem aprendermos o significado da palavra &#8220;paz&#8221;. A tecnologia avan\u00c3\u00a7ou,<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[9,4,5,3,8,6],"tags":[],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4elUM-4k","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.abrademi.com\/index.php\/wp-json\/wp\/v2\/posts\/268"}],"collection":[{"href":"https:\/\/www.abrademi.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abrademi.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abrademi.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abrademi.com\/index.php\/wp-json\/wp\/v2\/comments?post=268"}],"version-history":[{"count":3,"href":"https:\/\/www.abrademi.com\/index.php\/wp-json\/wp\/v2\/posts\/268\/revisions"}],"predecessor-version":[{"id":725,"href":"https:\/\/www.abrademi.com\/index.php\/wp-json\/wp\/v2\/posts\/268\/revisions\/725"}],"wp:attachment":[{"href":"https:\/\/www.abrademi.com\/index.php\/wp-json\/wp\/v2\/media?parent=268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abrademi.com\/index.php\/wp-json\/wp\/v2\/categories?post=268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abrademi.com\/index.php\/wp-json\/wp\/v2\/tags?post=268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}